{"id":633,"date":"2018-12-13T16:35:05","date_gmt":"2018-12-13T19:35:05","guid":{"rendered":"http:\/\/filtrocapacitivo.com.br\/blog\/?p=633"},"modified":"2018-12-13T17:09:18","modified_gmt":"2018-12-13T20:09:18","slug":"governo-atualiza-custo-a-ser-incluido-na-tarifa-de-repasse-itaipu-em-2019","status":"publish","type":"post","link":"https:\/\/filtrocapacitivo.com.br\/blog\/governo-atualiza-custo-a-ser-incluido-na-tarifa-de-repasse-itaipu-em-2019\/","title":{"rendered":"Governo atualiza custo a ser inclu\u00eddo na tarifa de repasse Itaipu em 2019"},"content":{"rendered":"<h2>O valor a ser acrescentado \u00e0 Tarifa de Repasse de Pot\u00eancia (TRP) de Itaipu e a ser praticado pela Eletrobras no pr\u00f3ximo ano ser\u00e1 de US$ 449,6 milh\u00f5es, que correspondem a US$ 3,4687\/kW.<\/h2>\n<p>O Governo Federal brasileiro publicou em edi\u00e7\u00e3o extra do Di\u00e1rio Oficial da Uni\u00e3o\u00a0da \u00faltima sexta-feira, 09\u00a0de novembro, a portaria interministerial n\u00ba4, dos minist\u00e9rios de Minas e Energia e da Fazenda, com a atualiza\u00e7\u00e3o de uma parte do custo a ser inclu\u00eddo na tarifa de repasse de pot\u00eancia da hidrel\u00e9trica Binacional Itaipu em 2019.<\/p>\n<p>O valor a ser acrescentado \u00e0 Tarifa de Repasse de Pot\u00eancia (TRP) de Itaipu e a ser praticado pela Eletrobras no pr\u00f3ximo ano ser\u00e1 de US$ 449,6 milh\u00f5es, que correspondem a US$ 3,4687\/kW. Para fins de compara\u00e7\u00e3o, o valor fixado em 2018 foi US$ 346,8 milh\u00f5es, que correspondeu a US$ 2,6605\/kW.<\/p>\n<p>A Tarifa de Repasse de Pot\u00eancia \u00e9 formada ainda pelo Custo Unit\u00e1rio dos Servi\u00e7os de Eletricidade da Itaipu (CUSE), que precisa ser fixado pelo Conselho de Itaipu, e a Taxa de Cess\u00e3o, que \u00e9 a remunera\u00e7\u00e3o paga ao Paraguai, pela energia cedida.<\/p>\n<p>O valor previsto pelo MME para acrescentar \u00e0 Tarifa de Repasse \u00e9 estabelecido anualmente desde 2007, para compensar a Eletrobras e o Tesouro Nacional pela retirada do fator anual do \u00edndice de reajuste da infla\u00e7\u00e3o americana.<\/p>\n<p>A Eletrobras n\u00e3o obt\u00e9m nem lucro nem preju\u00edzo com a comercializa\u00e7\u00e3o da energia de Itaipu. Se a chamada Conta de Comercializa\u00e7\u00e3o da Energia El\u00e9trica de Itaipu, ao final do exerc\u00edcio, apresentar resultado positivo, ser\u00e1 destinado \u00e0 modicidade tarif\u00e1ria dos consumidores das classes residencial e rural, com consumo mensal inferior a 350 kWh. J\u00e1 se o resultado for negativo, \u200bser\u00e1 incorporado pela Aneel, no c\u00e1lculo da TRP do pr\u00f3ximo exerc\u00edcio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O valor a ser acrescentado \u00e0 Tarifa de Repasse de Pot\u00eancia (TRP) de Itaipu e a ser praticado pela Eletrobras no pr\u00f3ximo ano ser\u00e1 de US$<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":652,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-633","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/filtrocapacitivo.com.br\/blog\/wp-json\/wp\/v2\/posts\/633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/filtrocapacitivo.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/filtrocapacitivo.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/filtrocapacitivo.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/filtrocapacitivo.com.br\/blog\/wp-json\/wp\/v2\/comments?post=633"}],"version-history":[{"count":1,"href":"https:\/\/filtrocapacitivo.com.br\/blog\/wp-json\/wp\/v2\/posts\/633\/revisions"}],"predecessor-version":[{"id":635,"href":"https:\/\/filtrocapacitivo.com.br\/blog\/wp-json\/wp\/v2\/posts\/633\/revisions\/635"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/filtrocapacitivo.com.br\/blog\/wp-json\/wp\/v2\/media\/652"}],"wp:attachment":[{"href":"https:\/\/filtrocapacitivo.com.br\/blog\/wp-json\/wp\/v2\/media?parent=633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/filtrocapacitivo.com.br\/blog\/wp-json\/wp\/v2\/categories?post=633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/filtrocapacitivo.com.br\/blog\/wp-json\/wp\/v2\/tags?post=633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}