{"id":898,"date":"2019-08-15T12:12:04","date_gmt":"2019-08-15T15:12:04","guid":{"rendered":"http:\/\/filtrocapacitivo.com.br\/blog\/?p=898"},"modified":"2019-08-09T19:13:28","modified_gmt":"2019-08-09T22:13:28","slug":"bandeira-tarifaria-sera-vermelha-para-agosto","status":"publish","type":"post","link":"https:\/\/filtrocapacitivo.com.br\/blog\/bandeira-tarifaria-sera-vermelha-para-agosto\/","title":{"rendered":"Bandeira tarif\u00e1ria ser\u00e1 vermelha para agosto"},"content":{"rendered":"\n<p>\nOs consumidores de energia el\u00e9trica \natendidos pelas concession\u00e1rias de todos pa\u00eds v\u00e3o pagar uma tarifa mais \ncara em agosto, informou a Ag\u00eancia Nacional de Energia El\u00e9trica (Aneel) \nnesta sexta-feira, 26 de julho. A bandeira tarif\u00e1ria em agosto de 2019 \nser\u00e1 vermelha, patamar 1, com custo de R$ 4,00 para cada 100 \nquilowatts-hora consumidos. Em julho, a bandeira foi amarela.\n&nbsp;\nAgosto \u00e9 um m\u00eas t\u00edpico da esta\u00e7\u00e3o seca \nnas principais bacias hidrogr\u00e1ficas do Sistema Interligado Nacional \n(SIN). A previs\u00e3o hidrol\u00f3gica para o m\u00eas sinaliza vaz\u00f5es abaixo da m\u00e9dia\n hist\u00f3rica e tend\u00eancia de redu\u00e7\u00e3o dos n\u00edveis dos principais \nreservat\u00f3rios. Esse cen\u00e1rio requer o aumento da gera\u00e7\u00e3o termel\u00e9trica, o \nque influenciou o aumento do pre\u00e7o da energia (PLD) e dos custos \nrelacionados ao risco hidrol\u00f3gico (GSF) em patamares condizentes com o \nda Bandeira Vermelha 1. O PLD e o GSF s\u00e3o as duas vari\u00e1veis que \ndeterminam a cor da bandeira a ser acionada.\n&nbsp;\nO sistema de bandeiras tarif\u00e1rias \nsinaliza o custo real da energia gerada para os consumidores do mercado \ncativo, possibilitando aos consumidores o bom uso da energia el\u00e9trica. O\n funcionamento das bandeiras tarif\u00e1rias \u00e9 simples: as cores verde, \namarela ou vermelha (nos patamares 1 e 2) indicam se a energia custar\u00e1 \nmais ou menos em fun\u00e7\u00e3o das condi\u00e7\u00f5es de gera\u00e7\u00e3o.\n\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os consumidores de energia el\u00e9trica atendidos pelas concession\u00e1rias de todos pa\u00eds v\u00e3o pagar uma tarifa mais cara em agosto, informou a Ag\u00eancia Nacional de Energia El\u00e9trica<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":899,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-898","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-filtros-capacitivos"],"_links":{"self":[{"href":"https:\/\/filtrocapacitivo.com.br\/blog\/wp-json\/wp\/v2\/posts\/898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/filtrocapacitivo.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/filtrocapacitivo.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/filtrocapacitivo.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/filtrocapacitivo.com.br\/blog\/wp-json\/wp\/v2\/comments?post=898"}],"version-history":[{"count":1,"href":"https:\/\/filtrocapacitivo.com.br\/blog\/wp-json\/wp\/v2\/posts\/898\/revisions"}],"predecessor-version":[{"id":900,"href":"https:\/\/filtrocapacitivo.com.br\/blog\/wp-json\/wp\/v2\/posts\/898\/revisions\/900"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/filtrocapacitivo.com.br\/blog\/wp-json\/wp\/v2\/media\/899"}],"wp:attachment":[{"href":"https:\/\/filtrocapacitivo.com.br\/blog\/wp-json\/wp\/v2\/media?parent=898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/filtrocapacitivo.com.br\/blog\/wp-json\/wp\/v2\/categories?post=898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/filtrocapacitivo.com.br\/blog\/wp-json\/wp\/v2\/tags?post=898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}